{"id":35870,"date":"2020-08-03T12:20:02","date_gmt":"2020-08-03T10:20:02","guid":{"rendered":"https:\/\/www.cigarjournal.com\/?p=35870"},"modified":"2020-08-03T12:20:02","modified_gmt":"2020-08-03T10:20:02","slug":"peter-rohner-ist-gestorben-ein-grosser-name-in-der-tabakbranche-wird-fehlen","status":"publish","type":"post","link":"https:\/\/www.cigarjournal.com\/de\/peter-rohner-ist-gestorben-ein-grosser-name-in-der-tabakbranche-wird-fehlen\/","title":{"rendered":"Peter Rohner ist gestorben, ein gro\u00dfer Name in der Tabakbranche wird fehlen"},"content":{"rendered":"<p>Als Peter Rohner am 23. September 1960 zur Welt kam, war sein Weg in der Tabakbranche noch nicht besiegelt, jedoch allenfalls geahnt. Wenige Wochen nach seiner Geburt schickten sich Vater Robert und Mutter Heidi Rohner an, in Rheineck ein eigenes selbst\u00e4ndiges Tabakgesch\u00e4ft zu er\u00f6ffnen und aufzubauen. Das Business war schon damals umk\u00e4mpft und entsprechend hart. Bereits als Kind half Peter im Gesch\u00e4ft t\u00fcchtig mit und seine Affinit\u00e4t f\u00fcr das Gesch\u00e4ftliche zeigte sich schon damals.<\/p>\n<p>Nach einer Banklehre und einer einj\u00e4hrigen T\u00e4tigkeit in der Zigarrenfabrik Brissago stieg er 1979 mit gerade mal 19 Jahren ins Gesch\u00e4ft seiner Eltern ein. Mit beispielloser Beharrlichkeit akquirierte er neue Kunden, baute vor allem auch das Automatennetz auf rund 200 Standorte eindr\u00fccklich aus und f\u00fchrte die computerunterst\u00fctzte Waren- und Finanzbuchhaltung ein, was damals f\u00fcr einen Kleinbetrieb ein Novum und eher revolution\u00e4r war.<\/p>\n<p>Als sein Vater, Robert Rohner, 1981 durch eine schwere Krankheit mitten aus seinem arbeitsreichen Leben gerissen wurde, \u00fcbernahm der junge Fachmann Peter das Gesch\u00e4ft. Er st\u00fcrzte sich mit dem ihm eigenen Durchhaltewillen und Enthusiasmus in die Arbeit. Die ersten Jahre waren steinig und von vielen R\u00fcckschl\u00e4gen gepr\u00e4gt, der Einsatz war so gro\u00df, dass es f\u00fcr anderw\u00e4rtige Belange und f\u00fcr allf\u00e4llige Freizeit keinen Platz hatte.<\/p>\n<p>Obwohl die Tabakbranche immer mehr mit Auflagen und Abgaben eingeengt und zerr\u00fcttet wurde, baute Peter Rohner sein Gesch\u00e4ft weiter aus. 1987 wagte er einen Riesenschritt nach vorne und erwarb das Traditionshaus &#8218;Wellauer &amp; Co. AG&#8216; in St. Gallen. Ab diesem Zeitpunkt wurden die Kunden unter dem Namen &#8218;Wellauer&#8216; beliefert und der Betrieb verlagerte seinen Schwerpunkt, weg vom vorwiegenden &#8218;Zigaretten Gro\u00dfhandel&#8216;, hin zu spezialisierten Produkten wie Tabak, Pfeifen und Zigarren. Zu den traditionellen beiden Fachgesch\u00e4ften &#8218;Marktplatz&#8216; und &#8218;St. Leonhard&#8216; in St. Gallen kamen noch drei weitere in Buchs, Olten und Z\u00fcrich hinzu.<\/p>\n<p>2002 erfolgte dann der Umzug von der Walenb\u00fcchelstra\u00dfe in St. Gallen nach Buchs in die Geb\u00e4ulichkeiten oberhalb des Tabakladens. Mit gro\u00dfem Einsatz und zusammen mit den engagierten und bew\u00e4hrten Mitarbeitern stellte Peter Rohner seine ganze Kraft in das Wohl der Firma. Mittlerweilen war aus der urspr\u00fcnglichen Einzelfirma mit einem Angestellten ein Betrieb mit \u00fcber 30 Mitarbeitenden entstanden. Peter Rohner war sich seiner sozialen Verantwortung gegen\u00fcber seinen Mitarbeitern und Mitarbeiterinnen besonders stark bewusst &#8212; ihr Wohlergehen und vor allen Dingen auch ihre soziale Absicherung waren ihm stets ein gro\u00dfes Anliegen.<\/p>\n<p>Als immer offensichtlicher wurde, dass die R\u00e4umlichkeiten in Buchs dem weiteren Wachstum der Firma nicht mehr gen\u00fcgten, wurde eine andere L\u00f6sung gesucht und gefunden. Die ehemalige &#8218;Schrubi&#8216;, ein ansehnliches Gesch\u00e4ftsgeb\u00e4ude mit entsprechend idealen R\u00e4umlichkeiten, konnte in Rheineck an der Thalerstra\u00dfe erworben werden. So schloss sich der Kreis und die prosperierende Firma fand \u00f6rtlich wieder zu ihren Wurzeln zur\u00fcck. Die engen Platzverh\u00e4ltnisse waren somit vorbei und der Umzug nach Rheineck erm\u00f6glichten eine gesunde Weiterentwicklung aller Gesch\u00e4ftsbereiche innerhalb der Branche wie Drehtabak, Pfeifentabak, Zigarren, Accessoires etc. Besonders stolz war Peter Rohner auf seine eigenen klassischen Tabakmischungen, die den Namen &#8218;Wellauer&#8216; in der ganzen Welt bekannt machten.<\/p>\n<p>Am 2. Juli 2020 mussten seine Mutter, seine Familie, seine in gro\u00dfer Anzahl anwesenden Freunde und besonders auch die vielen Gesch\u00e4ftspartner aus aller Welt von einem gro\u00dfartigen Menschen Abschied nehmen. Er war ein Mensch mit weitem Herzen. Mit seinem breit ausgepr\u00e4gten sozialen Gedankengut allen Menschen gegen\u00fcber, k\u00fcmmerte sich Peter Rohner seit dem Tod seines Vaters vor 39 Jahren umsichtig und r\u00fchrend um seine Mutter Heidi &#8212; und wenn&#8217;s Not tat, auch um seine Geschwister.<\/p>\n<p>Sein gro\u00dfes Wissen, seine \u00fcberragenden F\u00e4higkeiten und seine strikte Bestimmtheit in menschlicher wie auch in beruflicher Hinsicht, beeindruckten sehr. Das Tabakgesch\u00e4ft war f\u00fcr ihn nicht nur eine T\u00e4tigkeit, sondern eine wahrhaftige Berufung. Mit menschlicher W\u00e4rme, umfassendem Fachwissen, Disziplin, bewusster Bestimmtheit und gegebenenfalls auch mit einer t\u00fcchtigen Prise Sturheit, f\u00fchrte er zusammen mit seinem eingeschworenen Team das Gesch\u00e4ft durch Wind und Wetter hin zum gro\u00dfartigen Erfolg von heute. Fredi Kellenberger, einer seiner engsten Freunde, sagte einmal:&#8220;Von 100 Leuten, die dieses Gesch\u00e4ft zu f\u00fchren beabsichtigt h\u00e4tten, h\u00e4tten es h\u00f6chstens 3 geschafft, zu \u00fcberleben. Unter diesen Dreien ist Peter Rohner der Eine, der es schaffte, nicht einfach nur zu \u00fcberleben, sondern Erfolg zu haben!&#8220;<\/p>\n<p>Peter Rohner verk\u00f6rperte das f\u00fcrsorgliche Gedankengut und den n\u00f6tigen unternehmerischen Sp\u00fcrsinn eines wahren Patrons, eines Patrons f\u00fcr die Menschen und eines gewieften Patrons f\u00fcr das Gesch\u00e4ft, eine Kategorie von Unternehmern, die man heute leider immer weniger antrifft.<\/p>\n<p>Peter Rohner verspr\u00fchte weise Lebensfreude, Freude am intensiven Gesch\u00e4ftsleben, Freude im Freundeskreis, Freude, zu Hause zu sein, Freude an der F\u00fcrsorglichkeit, Freude an der Gem\u00fctlichkeit und nicht zuletzt, Freude an sch\u00f6nen Dingen, an Musik, sch\u00f6nem Wohnen und behaglichen Reisen.<\/p>\n<p>Vor kurzer Zeit &#8212; urpl\u00f6tzlich und vollkommen unerwartet &#8212; verlor er innerhalb weniger Tagen viel K\u00f6rpergewicht. Er erm\u00fcdete zusehends. Seine Haltung mit seiner gewohnten Aussage: &#8222;Das kommt dann schon wieder gut!&#8220; bewahrheitete sich leider nicht mehr. Trotz \u00e4rztlichem Beistand verstarb er am Donnerstag, 18. Juni 2020, in seinem Bett zuhause auf dem Hellb\u00fcchel.<\/p>\n<p>Er hinterl\u00e4sst in allen Bereichen eine gro\u00dfe L\u00fccke, die sich nur schwer f\u00fcllen l\u00e4sst. Peter Rohner wird uns allen fehlen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Peter Rohner ist gestorben, ein gro\u00dfer Name in der Tabakbranche wird fehlen<\/p>\n","protected":false},"author":6,"featured_media":35871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[1],"tags":[6272,6273],"_links":{"self":[{"href":"https:\/\/www.cigarjournal.com\/de\/wp-json\/wp\/v2\/posts\/35870"}],"collection":[{"href":"https:\/\/www.cigarjournal.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cigarjournal.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cigarjournal.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cigarjournal.com\/de\/wp-json\/wp\/v2\/comments?post=35870"}],"version-history":[{"count":0,"href":"https:\/\/www.cigarjournal.com\/de\/wp-json\/wp\/v2\/posts\/35870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cigarjournal.com\/de\/wp-json\/wp\/v2\/media\/35871"}],"wp:attachment":[{"href":"https:\/\/www.cigarjournal.com\/de\/wp-json\/wp\/v2\/media?parent=35870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cigarjournal.com\/de\/wp-json\/wp\/v2\/categories?post=35870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cigarjournal.com\/de\/wp-json\/wp\/v2\/tags?post=35870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}